{"id":12763,"date":"2021-11-04T15:48:51","date_gmt":"2021-11-04T14:48:51","guid":{"rendered":"https:\/\/biosaltpearls.com\/kontakt\/"},"modified":"2022-09-22T10:06:38","modified_gmt":"2022-09-22T08:06:38","slug":"kontakt","status":"publish","type":"page","link":"https:\/\/biosaltpearls.com\/pl\/kontakt\/","title":{"rendered":"Kontakt"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"12763\" class=\"elementor elementor-12763 elementor-8800\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"wd-negative-gap elementor-section elementor-top-section elementor-element elementor-element-36b418b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"36b418b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-5fecf3d\" data-id=\"5fecf3d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e2e98f1 wd-width-100 elementor-widget elementor-widget-wd_title\" data-id=\"e2e98f1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"title-wrapper wd-set-mb reset-last-child wd-title-color-default wd-title-style-default wd-title-size-default text-left\">\n\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<h4 class=\"woodmart-title-container title wd-fontsize-l\">Gdzie jeste\u015bmy?<\/h4> \n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"wd-negative-gap elementor-section elementor-inner-section elementor-element elementor-element-fe15c48 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fe15c48\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-bec6bf4\" data-id=\"bec6bf4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cc77b11 wd-width-100 elementor-widget elementor-widget-wd_title\" data-id=\"cc77b11\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"title-wrapper wd-set-mb reset-last-child wd-title-color-default wd-title-style-default wd-title-size-default text-left\">\n\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<h4 class=\"woodmart-title-container title wd-fontsize-l\"><strong>C\u00e1diz<\/strong><\/h4> \n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"title-after_title reset-last-child wd-fontsize-xs\">\n\t\t\t\t\t<p>Calle Alexandro Humbold, N\u00ba 12 (Pol\u00edgono Industrial Salinas de Poniente), 11500, El Puerto de Santa Mar\u00eda<\/p>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2bfa1cb elementor-widget elementor-widget-wd_text_block\" data-id=\"2bfa1cb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_text_block.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"wd-text-block reset-last-child text-left\">\n\t\t\t\n\t\t\t<p><span style=\"color: #333333;\"><strong>Email:<\/strong><\/span> info@biosaltpearls.com<br><span style=\"color: #333333;\"><strong>Tel\u00e9fono:<\/strong><\/span> (+34) 856 925 095<\/p><p><span style=\"color: #333333;\"><strong>Opieka nad konsumentami<\/strong><\/span><br>Od poniedzia\u0142ku do pi\u0105tku w godzinach 8:00-15:00<\/p>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-a14506f wd-width-100 elementor-widget elementor-widget-wd_title\" data-id=\"a14506f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"title-wrapper wd-set-mb reset-last-child wd-title-color-default wd-title-style-default wd-title-size-default text-left\">\n\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<h4 class=\"woodmart-title-container title wd-fontsize-l\">Kontakt z nami<\/h4> \n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cf530b0 elementor-widget elementor-widget-wd_text_block\" data-id=\"cf530b0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_text_block.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"wd-text-block reset-last-child text-left\">\n\t\t\t\n\t\t\t<p>Je\u015bli masz jakie\u015b pytania, kt\u00f3re nie zosta\u0142y odpowiedzia\u0142 na tej stronie lub chcesz uzyska\u0107 wi\u0119cej informacji na temat BioSalt Pearls, prosimy o skorzystanie z poni\u017cszego formularza, aby wys\u0142a\u0107 nam pytania, kt\u00f3re chcia\u0142by\u015b, aby\u015bmy adresowali. Prosz\u0119 wype\u0142ni\u0107 wszystkie pola oznaczone gwiazdk\u0105 (*).<\/p>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d9fb016 elementor-widget elementor-widget-wd_popup\" data-id=\"d9fb016\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_popup.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"wd-button-wrapper text-left\" >\n\t\t\t<a class=\"btn btn-style-default btn-shape-rectangle btn-size-default wd-open-popup btn-color-primary btn-icon-pos-right\"  href=\"#popup-5ef9ab74e822b\">\n\t\t\t\t<span class=\"wd-btn-text\" data-elementor-setting-key=\"text\">\n\t\t\t\t\tEscr\u00edbenos un mensaje\t\t\t\t<\/span>\n\n\t\t\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div id=\"popup-5ef9ab74e822b\" class=\"wd-popup wd-popup-element wd-entry-content mfp-hide\" style=\"--wd-popup-width:900px;\">\n\t\t\t\t\t\t\t<link rel=\"stylesheet\" id=\"elementor-post-1570-css\" href=\"https:\/\/biosaltpearls.com\/wp-content\/uploads\/elementor\/css\/post-1570.css?ver=1784116976\" type=\"text\/css\" media=\"all\">\n\t\t\t\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"1570\" class=\"elementor elementor-1570\" data-elementor-post-type=\"cms_block\">\n\t\t\t\t\t\t<section class=\"wd-negative-gap elementor-section elementor-top-section elementor-element elementor-element-25dc3f7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"25dc3f7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-748fb66\" data-id=\"748fb66\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b530a3c wd-width-100 elementor-widget elementor-widget-wd_title\" data-id=\"b530a3c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"title-wrapper wd-set-mb reset-last-child wd-title-color-default wd-title-style-default wd-title-size-small text-left\">\n\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<h4 class=\"woodmart-title-container title wd-fontsize-m\">ENV\u00cdANOS UN MENSAJE<\/h4> \n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a5ee9cc elementor-widget elementor-widget-wd_contact_form_7\" data-id=\"a5ee9cc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_contact_form_7.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f1572-o1\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"1572\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/pl\/wp-json\/wp\/v2\/pages\/12763#wpcf7-f1572-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"1572\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.6\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f1572-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/fieldset>\n<div class=\"row\">\n\t<p class=\"col-md-6\"><label>Nombre<\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span>\n\t<\/p>\n\t<p class=\"col-md-6\"><label>Email<\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span>\n\t<\/p>\n<\/div>\n<div class=\"row\">\n\t<p class=\"col-md-6\"><label>Tel\u00e9fono (opcional)<\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"tel-767\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-tel wpcf7-text wpcf7-validates-as-tel\" aria-invalid=\"false\" value=\"\" type=\"tel\" name=\"tel-767\" \/><\/span>\n\t<\/p>\n\t<p class=\"col-md-6\"><label>Empresa (opcional)<\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"text-1\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"text-1\" \/><\/span>\n\t<\/p>\n<\/div>\n<p><label>Mensaje<\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" name=\"your-message\"><\/textarea><\/span>\n<\/p>\n<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner btn\" type=\"submit\" value=\"Enviar mensaje\" \/>\n<\/p>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"privacidad-816\"><span class=\"wpcf7-form-control wpcf7-acceptance\"><span class=\"wpcf7-list-item\"><label><input type=\"checkbox\" name=\"privacidad-816\" value=\"1\" aria-invalid=\"false\" \/><span class=\"wpcf7-list-item-label\">He le\u00eddo y acepto la pol\u00edtica de privacidad *<\/span><\/label><\/span><\/span><\/span><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"publicidad-586\"><span class=\"wpcf7-form-control wpcf7-acceptance optional\"><span class=\"wpcf7-list-item\"><label><input type=\"checkbox\" name=\"publicidad-586\" value=\"1\" aria-invalid=\"false\" \/><span class=\"wpcf7-list-item-label\">Consiento de manera previa y expresa que me env\u00eden comunicaciones comerciales sobre sus productos y servicios.<\/span><\/label><\/span><\/span><\/span>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-40b71ea color-scheme-light\" data-id=\"40b71ea\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cc47e65 wd-width-100 elementor-widget elementor-widget-wd_title\" data-id=\"cc47e65\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"title-wrapper wd-set-mb reset-last-child wd-title-color-white wd-title-style-default wd-title-size-small text-left\">\n\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<h4 class=\"woodmart-title-container title wd-fontsize-m\">INFORMACI\u00d3N DE CONTACTO<\/h4> \n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-313f937 elementor-widget elementor-widget-wd_infobox\" data-id=\"313f937\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_infobox.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"info-box-wrapper\">\n\t\t\t<div class=\"wd-info-box text-left box-icon-align-left box-style-base color-scheme- wd-items-top\">\n\t\t\t\t\t\t\t\t\t<div class=\"box-icon-wrapper  box-with-icon box-icon-simple\">\n\t\t\t\t\t\t<div class=\"info-box-icon\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"info-svg-wrapper\" style=\"width:30px; height:30px;\"><img loading=\"lazy\" decoding=\"async\"  src=\"https:\/\/biosaltpearls.com\/wp-content\/uploads\/2021\/09\/wd-pointer.svg\" title=\"wd-pointer\" loading=\"lazy\" width=\"30\" height=\"30\"><\/div>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<div class=\"info-box-content\">\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"info-box-inner reset-last-child\"data-elementor-setting-key=\"content\"><p>Pol. Ind. Salinas de Poniente. Alexander Humboldt, N\u00ba 12. El Puerto de Santa Mar\u00eda, C\u00e1diz 11500<\/p>\n<\/div>\n\n\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-996d64c elementor-widget elementor-widget-wd_infobox\" data-id=\"996d64c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_infobox.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"info-box-wrapper\">\n\t\t\t<div class=\"wd-info-box text-left box-icon-align-left box-style-base color-scheme- wd-items-top\">\n\t\t\t\t\t\t\t\t\t<div class=\"box-icon-wrapper  box-with-icon box-icon-simple\">\n\t\t\t\t\t\t<div class=\"info-box-icon\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"info-svg-wrapper\" style=\"width:30px; height:30px;\"><img loading=\"lazy\" decoding=\"async\"  src=\"https:\/\/biosaltpearls.com\/wp-content\/uploads\/2021\/09\/wd-mobile.svg\" title=\"wd-mobile\" loading=\"lazy\" width=\"30\" height=\"30\"><\/div>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<div class=\"info-box-content\">\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"info-box-inner reset-last-child\"data-elementor-setting-key=\"content\"><p><span class=\"list-content\">(+34) 856 92 50 95<\/span><\/p>\n<\/div>\n\n\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t<a href=\"tel:+34856925095\" class=\"wd-info-box-link wd-fill\" aria-label=\"Infobox link\"><\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e4b1629 elementor-widget elementor-widget-wd_infobox\" data-id=\"e4b1629\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_infobox.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"info-box-wrapper\">\n\t\t\t<div class=\"wd-info-box text-left box-icon-align-left box-style-base color-scheme- wd-items-top\">\n\t\t\t\t\t\t\t\t\t<div class=\"box-icon-wrapper  box-with-icon box-icon-simple\">\n\t\t\t\t\t\t<div class=\"info-box-icon\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"info-svg-wrapper\" style=\"width:30px; height:30px;\"><img loading=\"lazy\" decoding=\"async\"  src=\"https:\/\/biosaltpearls.com\/wp-content\/uploads\/2021\/09\/wd-paper-plane.svg\" title=\"wd-paper-plane\" loading=\"lazy\" width=\"30\" height=\"30\"><\/div>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<div class=\"info-box-content\">\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"info-box-inner reset-last-child\"data-elementor-setting-key=\"content\"><p><span class=\"list-content\">info@biosaltpearls.com<\/span><\/p>\n<\/div>\n\n\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t<a href=\"mailto:info@biosaltpearls.com\" class=\"wd-info-box-link wd-fill\" aria-label=\"Infobox link\"><\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5a90c09 color-scheme-light text-left elementor-widget elementor-widget-text-editor\" data-id=\"5a90c09\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Le informamos que el responsable del tratamiento de estos datos es NORTEM CHEM, S.A y la finalidad de este es la gesti\u00f3n, estudio y resoluci\u00f3n de las consultas efectuadas y, en caso de que as\u00ed expresamente lo consienta marcando la casilla al efecto, para el env\u00edo de comunicaciones comerciales de nuestros productos y servicios, encontr\u00e1ndonos legitimados para este tratamiento a trav\u00e9s del consentimiento que nos est\u00e1 otorgando en este acto. No se ceder\u00e1n datos a terceros salvo obligaci\u00f3n legal. Usted certifica que es mayor de 14 a\u00f1os y que por lo tanto posee la capacidad legal necesaria para la prestaci\u00f3n de este consentimiento y todo ello, de conformidad con lo establecido en la Pol\u00edtica de Privacidad. Puede usted acceder, rectificar y suprimir los datos, as\u00ed como otros derechos, como se explica en la informaci\u00f3n adicional. Puede consultar la informaci\u00f3n adicional y detallada sobre Protecci\u00f3n de Datos pinchando aqu\u00ed\u00a0<a href=\"https:\/\/biosaltpearls.com\/\/politica-privacidad\/\">+ info<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-1754685\" data-id=\"1754685\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c8ce354 elementor-widget elementor-widget-html\" data-id=\"c8ce354\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<iframe src=\"https:\/\/www.google.com\/maps\/embed?pb=!1m18!1m12!1m3!1d3202.8564306129847!2d-6.198158685365606!3d36.60576668632117!2m3!1f0!2f0!3f0!3m2!1i1024!2i768!4f13.1!3m3!1m2!1s0xd0dcf9de66a4e6b%3A0x6e21f40a1fd01d87!2sNortem%20Biotechnology!5e0!3m2!1ses!2ses!4v1654232529119!5m2!1ses!2ses\" width=\"800\" height=\"650\" style=\"border:0;\" allowfullscreen=\"\" loading=\"lazy\" referrerpolicy=\"no-referrer-when-downgrade\"><\/iframe>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Gdzie jeste\u015bmy? C\u00e1diz Calle Alexandro Humbold, N\u00ba 12 (Pol\u00edgono Industrial Salinas de Poniente), 11500, El Puerto de Santa Mar\u00eda Email:<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_crdt_document":"","footnotes":""},"class_list":["post-12763","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Kontakt - BioSalt Nortem Pearls<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/biosaltpearls.com\/pl\/kontakt\/\" \/>\n<meta property=\"og:locale\" content=\"pl_PL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Kontakt - BioSalt Nortem Pearls\" \/>\n<meta property=\"og:description\" content=\"Gdzie jeste\u015bmy? C\u00e1diz Calle Alexandro Humbold, N\u00ba 12 (Pol\u00edgono Industrial Salinas de Poniente), 11500, El Puerto de Santa Mar\u00eda Email:\" \/>\n<meta property=\"og:url\" content=\"https:\/\/biosaltpearls.com\/pl\/kontakt\/\" \/>\n<meta property=\"og:site_name\" content=\"BioSalt Nortem Pearls\" \/>\n<meta property=\"article:modified_time\" content=\"2022-09-22T08:06:38+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Szacowany czas czytania\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuty\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/biosaltpearls.com\\\/pl\\\/kontakt\\\/\",\"url\":\"https:\\\/\\\/biosaltpearls.com\\\/pl\\\/kontakt\\\/\",\"name\":\"Kontakt - BioSalt Nortem Pearls\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/biosaltpearls.com\\\/pl\\\/#website\"},\"datePublished\":\"2021-11-04T14:48:51+00:00\",\"dateModified\":\"2022-09-22T08:06:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/biosaltpearls.com\\\/pl\\\/kontakt\\\/#breadcrumb\"},\"inLanguage\":\"pl-PL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/biosaltpearls.com\\\/pl\\\/kontakt\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/biosaltpearls.com\\\/pl\\\/kontakt\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/biosaltpearls.com\\\/pl\\\/organiczna-sol-morska-z-pierwszego-tloczenia-biosalt-pearls\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Kontakt\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/biosaltpearls.com\\\/pl\\\/#website\",\"url\":\"https:\\\/\\\/biosaltpearls.com\\\/pl\\\/\",\"name\":\"BioSalt Nortem Pearls\",\"description\":\"Perlas de Sal Marina Virgen Ecol\u00f3gica\",\"publisher\":{\"@id\":\"https:\\\/\\\/biosaltpearls.com\\\/pl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/biosaltpearls.com\\\/pl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pl-PL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/biosaltpearls.com\\\/pl\\\/#organization\",\"name\":\"BioSalt Pearls\",\"url\":\"https:\\\/\\\/biosaltpearls.com\\\/pl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pl-PL\",\"@id\":\"https:\\\/\\\/biosaltpearls.com\\\/pl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/biosaltpearls.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/biosalt-perlas-sal-marina-virgen-natural-ecologica.jpg\",\"contentUrl\":\"https:\\\/\\\/biosaltpearls.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/biosalt-perlas-sal-marina-virgen-natural-ecologica.jpg\",\"width\":1000,\"height\":1000,\"caption\":\"BioSalt Pearls\"},\"image\":{\"@id\":\"https:\\\/\\\/biosaltpearls.com\\\/pl\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/instagram.com\\\/biosalt\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Kontakt - BioSalt Nortem Pearls","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/biosaltpearls.com\/pl\/kontakt\/","og_locale":"pl_PL","og_type":"article","og_title":"Kontakt - BioSalt Nortem Pearls","og_description":"Gdzie jeste\u015bmy? C\u00e1diz Calle Alexandro Humbold, N\u00ba 12 (Pol\u00edgono Industrial Salinas de Poniente), 11500, El Puerto de Santa Mar\u00eda Email:","og_url":"https:\/\/biosaltpearls.com\/pl\/kontakt\/","og_site_name":"BioSalt Nortem Pearls","article_modified_time":"2022-09-22T08:06:38+00:00","twitter_card":"summary_large_image","twitter_misc":{"Szacowany czas czytania":"2 minuty"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/biosaltpearls.com\/pl\/kontakt\/","url":"https:\/\/biosaltpearls.com\/pl\/kontakt\/","name":"Kontakt - BioSalt Nortem Pearls","isPartOf":{"@id":"https:\/\/biosaltpearls.com\/pl\/#website"},"datePublished":"2021-11-04T14:48:51+00:00","dateModified":"2022-09-22T08:06:38+00:00","breadcrumb":{"@id":"https:\/\/biosaltpearls.com\/pl\/kontakt\/#breadcrumb"},"inLanguage":"pl-PL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/biosaltpearls.com\/pl\/kontakt\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/biosaltpearls.com\/pl\/kontakt\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/biosaltpearls.com\/pl\/organiczna-sol-morska-z-pierwszego-tloczenia-biosalt-pearls\/"},{"@type":"ListItem","position":2,"name":"Kontakt"}]},{"@type":"WebSite","@id":"https:\/\/biosaltpearls.com\/pl\/#website","url":"https:\/\/biosaltpearls.com\/pl\/","name":"BioSalt Nortem Pearls","description":"Perlas de Sal Marina Virgen Ecol\u00f3gica","publisher":{"@id":"https:\/\/biosaltpearls.com\/pl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/biosaltpearls.com\/pl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pl-PL"},{"@type":"Organization","@id":"https:\/\/biosaltpearls.com\/pl\/#organization","name":"BioSalt Pearls","url":"https:\/\/biosaltpearls.com\/pl\/","logo":{"@type":"ImageObject","inLanguage":"pl-PL","@id":"https:\/\/biosaltpearls.com\/pl\/#\/schema\/logo\/image\/","url":"https:\/\/biosaltpearls.com\/wp-content\/uploads\/2022\/11\/biosalt-perlas-sal-marina-virgen-natural-ecologica.jpg","contentUrl":"https:\/\/biosaltpearls.com\/wp-content\/uploads\/2022\/11\/biosalt-perlas-sal-marina-virgen-natural-ecologica.jpg","width":1000,"height":1000,"caption":"BioSalt Pearls"},"image":{"@id":"https:\/\/biosaltpearls.com\/pl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/instagram.com\/biosalt"]}]}},"_links":{"self":[{"href":"https:\/\/biosaltpearls.com\/pl\/wp-json\/wp\/v2\/pages\/12763","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/biosaltpearls.com\/pl\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/biosaltpearls.com\/pl\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/biosaltpearls.com\/pl\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/biosaltpearls.com\/pl\/wp-json\/wp\/v2\/comments?post=12763"}],"version-history":[{"count":1,"href":"https:\/\/biosaltpearls.com\/pl\/wp-json\/wp\/v2\/pages\/12763\/revisions"}],"predecessor-version":[{"id":12764,"href":"https:\/\/biosaltpearls.com\/pl\/wp-json\/wp\/v2\/pages\/12763\/revisions\/12764"}],"wp:attachment":[{"href":"https:\/\/biosaltpearls.com\/pl\/wp-json\/wp\/v2\/media?parent=12763"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}